{"id":697,"date":"2024-08-25T09:36:30","date_gmt":"2024-08-25T08:36:30","guid":{"rendered":"https:\/\/ecoforest.com\/?p=697"},"modified":"2026-02-10T14:58:09","modified_gmt":"2026-02-10T13:58:09","slug":"que-es-la-aerotermia-cuales-son-sus-ventajas","status":"publish","type":"post","link":"https:\/\/ecoforest.com\/es\/blog\/que-es-la-aerotermia-cuales-son-sus-ventajas\/","title":{"rendered":"Qu\u00e9 es la Aerotermia y c\u00f3mo funciona: Ventajas y desventajas de su instalaci\u00f3n"},"content":{"rendered":"\n<p><strong>La aerotermia es un sistema de climatizaci\u00f3n que aprovecha la energ\u00eda presente en el aire exterior para generar calefacci\u00f3n, refrigeraci\u00f3n y agua caliente sanitaria (ACS)<\/strong>. Su funcionamiento se basa en una bomba de calor, la cual extrae calor del aire del entorno y lo transfiere al interior de un edificio para calentarlo, o realiza el proceso inverso para refrigerarlo.<\/p>\n\n\n\n<p>En la era de la energ\u00eda limpia y sostenible, comprender este sistema se ha vuelto fundamental, revel\u00e1ndose como una alternativa prometedora. <strong>Esta fuente de energ\u00eda no solo proporciona calefacci\u00f3n y agua caliente en los hogares que la eligen, sino que tambi\u00e9n reduce el impacto medioambiental y el coste de la factura de la luz al final de cada mes.<\/strong><\/p>\n\n\n\n<p>En este art\u00edculo, profundizaremos en los detalles m\u00e1s importantes para entender su funcionamiento, sus aplicaciones, as\u00ed como las ventajas y desventajas de su instalaci\u00f3n.<\/p>\n\n\n\n<p>Si tienes cualquier duda, te invitamos a seguir leyendo y, si lo deseas, puedes ponerte en contacto con nuestro equipo de expertos, quienes te asesorar\u00e1n sobre c\u00f3mo la aerotermia puede ser la soluci\u00f3n ideal para tu situaci\u00f3n actual.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es la aerotermia?<\/h2>\n\n\n\n<p>La aerotermia es una tecnolog\u00eda emergente que est\u00e1 revolucionando la manera en que calentamos y enfriamos nuestros hogares, proporcionando una alternativa ecol\u00f3gica y altamente eficiente a los sistemas tradicionales de calefacci\u00f3n y refrigeraci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>En su esencia, la aerotermia es una tecnolog\u00eda que <strong>extrae la energ\u00eda presente en el aire exterior,<\/strong> incluso en condiciones de baja temperatura, y la convierte en calor o fr\u00edo para ser utilizada en nuestras viviendas.&nbsp;<\/p>\n\n\n\n<p>Esta extracci\u00f3n de energ\u00eda se realiza mediante una<strong> bomba de calor aerot\u00e9rmica.<\/strong><\/p>\n\n\n\n<p>Es importante mencionar que la aerotermia no genera calor por s\u00ed misma, sino que traslada y amplifica el calor presente en el ambiente, lo que la hace incre\u00edblemente eficiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfY c\u00f3mo funciona la aerotermia?<\/h2>\n\n\n\n<p>El concepto b\u00e1sico detr\u00e1s de la aerotermia puede parecer casi dif\u00edcil de creer para muchos: <strong>extraer energ\u00eda del aire, i<\/strong>ncluso cuando est\u00e1 fr\u00edo, y usarla para calentar o enfriar nuestros hogares.<\/p>\n\n\n\n<p>Aunque puede sonar sorprendente, esta tecnolog\u00eda se basa en principios termodin\u00e1micos bien establecidos.&nbsp;<\/p>\n\n\n\n<p>Toma nota: <strong>el principio b\u00e1sico es la bomba de calor.<\/strong><\/p>\n\n\n\n<p>La pieza central de un sistema aerot\u00e9rmico es la bomba de calor.&nbsp;<\/p>\n\n\n\n<p>Aunque el nombre pueda inducir a pensar en la generaci\u00f3n de calor, en realidad, lo que hace una bomba de calor es transferir energ\u00eda t\u00e9rmica de un lugar a otro.&nbsp;<\/p>\n\n\n\n<p>Esta transferencia se basa en el ciclo de refrigeraci\u00f3n, similar al utilizado en frigor\u00edficos o aires acondicionados.<\/p>\n\n\n\n<p>Para entender su funcionamiento, es fundamental conocer los componentes de la bomba de calor y los tipos de sistemas de calefacci\u00f3n disponibles.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1-1024x683.jpg\" alt=\"que es la aerotermia y como funciona\" class=\"wp-image-36311\" title=\"\" srcset=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1-1024x683.jpg 1024w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1-300x200.jpg 300w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1-768x512.jpg 768w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1-1536x1024.jpg 1536w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Ciclo de refrigeraci\u00f3n y fluido refrigerante<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Evaporaci\u00f3n:<\/strong> El fluido refrigerante, a baja temperatura y presi\u00f3n, entra en el evaporador, donde absorbe el calor del aire exterior y se evapora. Aunque pueda parecer contradictorio, incluso el aire fr\u00edo contiene energ\u00eda t\u00e9rmica que puede ser aprovechada.<\/li>\n\n\n\n<li><strong>Compresi\u00f3n<\/strong>: Una vez que el refrigerante se ha evaporado y ha absorbido calor, es comprimido por un compresor. Al comprimirse, su temperatura y presi\u00f3n aumentan significativamente.<\/li>\n\n\n\n<li><strong>Condensaci\u00f3n:<\/strong> El refrigerante caliente y a alta presi\u00f3n pasa por el condensador, donde cede su calor al sistema de calefacci\u00f3n del edificio, ya sea a un circuito de agua para radiadores o suelo radiante, o directamente al aire en sistemas de aire acondicionado. Durante este proceso, el refrigerante se condensa y vuelve a estado l\u00edquido.<\/li>\n\n\n\n<li><strong>Expansi\u00f3n:<\/strong> Finalmente, el refrigerante pasa por una v\u00e1lvula de expansi\u00f3n, donde su presi\u00f3n y temperatura disminuyen antes de regresar al evaporador y comenzar el ciclo nuevamente.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfFunciona tanto en invierno como en verano?<\/h3>\n\n\n\n<p>Un aspecto interesante de la aerotermia es su versatilidad.&nbsp;<\/p>\n\n\n\n<p>Dependiendo de la necesidad, la bomba de calor puede operar en modo de calefacci\u00f3n en invierno o en <a href=\"https:\/\/ecoforest.com\/es\/blog\/refresca-tu-casa-este-verano-con-aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/blog\/refresca-tu-casa-este-verano-con-aerotermia\/\">modo de refrigeraci\u00f3n en verano<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Invierno:<\/strong> En esta temporada, el objetivo es calentar el hogar. Por ello, la bomba de calor extrae la energ\u00eda t\u00e9rmica del aire exterior, incluso si est\u00e1 fr\u00edo, y la transfiere al interior de la vivienda.<\/li>\n\n\n\n<li><strong>Verano:<\/strong> Durante los meses m\u00e1s calurosos, el proceso se invierte. La bomba de calor extrae el calor del interior de la vivienda y lo transfiere al exterior, enfriando as\u00ed el ambiente interior.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Eficiencia y coeficiente de rendimiento (COP)<\/h3>\n\n\n\n<p>Una de las maravillas de la aerotermia es su eficiencia.&nbsp;<\/p>\n\n\n\n<p>El coeficiente de rendimiento (COP) mide la relaci\u00f3n entre la energ\u00eda obtenida en forma de calor y la energ\u00eda el\u00e9ctrica consumida.&nbsp;<\/p>\n\n\n\n<p>En muchos sistemas aerot\u00e9rmicos, el COP puede ser de 3 o 4, lo que significa que por cada unidad de energ\u00eda el\u00e9ctrica consumida, se obtienen 3 o 4 unidades de energ\u00eda t\u00e9rmica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principales componentes de la bomba de calor<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Evaporador: <\/strong>Es el intercambiador de calor donde el fluido refrigerante absorbe y recoge el calor del medio (que puede ser el aire, agua o tierra, seg\u00fan el tipo de bomba de calor). En este componente, el refrigerante se evapora, pasando de l\u00edquido a gas, mientras toma energ\u00eda t\u00e9rmica del entorno.<\/li>\n\n\n\n<li><strong>Compresor:<\/strong> Una vez que el refrigerante se ha evaporado y ha absorbido calor, se traslada al compresor. Este componente tiene la funci\u00f3n de comprimir el gas refrigerante, lo que provoca que aumente su temperatura y presi\u00f3n.<\/li>\n\n\n\n<li><strong>Condensador: <\/strong>Es otro intercambiador de calor, pero en este caso, el refrigerante cede el calor al medio que se desea calentar (por ejemplo, el aire o agua de una vivienda). Al perder esta energ\u00eda t\u00e9rmica, el refrigerante se condensa y vuelve a su estado l\u00edquido.<\/li>\n\n\n\n<li><strong>V\u00e1lvula de expansi\u00f3n (o dispositivo de expansi\u00f3n)<\/strong>: Este componente regula el flujo del refrigerante l\u00edquido y reduce su presi\u00f3n antes de que entre de nuevo en el evaporador, iniciando as\u00ed otro ciclo. Durante este proceso, la temperatura del refrigerante tambi\u00e9n disminuye.<\/li>\n\n\n\n<li><strong>Circuito de refrigerante: <\/strong>Es el sistema de tuber\u00edas por donde circula el refrigerante entre los diferentes componentes. Est\u00e1 dise\u00f1ado para soportar los cambios de presi\u00f3n y temperatura a los que se somete el refrigerante durante el ciclo.<\/li>\n\n\n\n<li><strong>Controlador o termostato:<\/strong> Es el \u00abcerebro\u00bb del sistema, y permite al usuario establecer la temperatura deseada. Regula el funcionamiento de la bomba de calor y asegura que se mantenga la temperatura adecuada.<\/li>\n\n\n\n<li><strong>Ventilador (en bombas de calor aire-aire): <\/strong>Este componente es esencial para permitir la circulaci\u00f3n del aire a trav\u00e9s del evaporador y\/o condensador en bombas de calor que utilizan aire como medio de transferencia.<\/li>\n\n\n\n<li><strong>Bomba de circulaci\u00f3n (en bombas de calor agua-agua o tierra-agua): <\/strong>Si la bomba de calor utiliza agua o un l\u00edquido anticongelante como medio de transferencia, este componente es necesario para mover dicho l\u00edquido a trav\u00e9s del sistema.<\/li>\n\n\n\n<li><strong>Desescarche:<\/strong> En bombas de calor que operan en climas fr\u00edos, puede formarse escarcha en el evaporador. Este sistema, ya sea mediante un ciclo inverso o resistencias el\u00e9ctricas, permite derretir esta escarcha y garantizar el funcionamiento eficiente del equipo.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de calefacci\u00f3n por aerotermia<\/h2>\n\n\n\n<p>La aerotermia se ha consolidado como una de las soluciones m\u00e1s eficientes y sostenibles para la climatizaci\u00f3n de espacios.&nbsp;<\/p>\n\n\n\n<p>Aprovecha la energ\u00eda del aire exterior para calentar o enfriar un ambiente y\/o proporcionar agua caliente sanitaria.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan la forma en que se distribuye el calor en el interior de una vivienda o edificio, se pueden identificar distintos sistemas de calefacci\u00f3n por aerotermia.&nbsp;<\/p>\n\n\n\n<p>A continuaci\u00f3n, se detallan los principales tipos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Suelo radiante:<\/h3>\n\n\n\n<p>Consiste en una red de tuber\u00edas instaladas bajo el suelo por donde circula agua caliente, calentando de forma uniforme la superficie y radiando calor al ambiente.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ventajas: <\/strong>Ofrece un calor homog\u00e9neo y confortable, es invisible (ya que est\u00e1 bajo el suelo), y es altamente eficiente, ya que funciona a bajas temperaturas.<\/li>\n\n\n\n<li><strong>Desventajas:<\/strong> Requiere una inversi\u00f3n inicial m\u00e1s alta y no es tan r\u00e1pido en respuesta como otros sistemas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Radiadores de baja temperatura<\/h3>\n\n\n\n<p>Son similares a los radiadores convencionales pero est\u00e1n dise\u00f1ados para trabajar eficientemente con agua a menor temperatura.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ventajas<\/strong>: Son una buena opci\u00f3n si se quiere cambiar un sistema de calefacci\u00f3n tradicional por aerotermia, aprovechando los radiadores existentes (aunque es recomendable verificar su compatibilidad).<\/li>\n\n\n\n<li><strong>Desventajas<\/strong>: Pueden no ser tan eficientes como el suelo radiante y su est\u00e9tica puede no ser del gusto de todos.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Fan coils o unidades de tratamiento de aire<\/h3>\n\n\n\n<p>Estos dispositivos son unidades interiores que incorporan un ventilador para impulsar el aire a trav\u00e9s de un intercambiador de calor, distribuyendo as\u00ed el calor en el espacio.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ventajas<\/strong>: Son vers\u00e1tiles, ya que pueden proporcionar tanto calefacci\u00f3n como refrigeraci\u00f3n, y ofrecen una respuesta r\u00e1pida.<\/li>\n\n\n\n<li><strong>Desventajas<\/strong>: Pueden generar algo de ruido debido al ventilador y requieren un mantenimiento regular de los filtros.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Sistemas de conductos<\/h3>\n\n\n\n<p>Utilizan conductos para distribuir el aire caliente (o fr\u00edo) desde una unidad centralizada a las diferentes estancias de la vivienda o edificio.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ventajas<\/strong>: Permiten climatizar toda la vivienda de forma uniforme y son invisibles, ya que los conductos suelen estar ocultos.<\/li>\n\n\n\n<li><strong>Desventajas<\/strong>: La instalaci\u00f3n inicial puede ser compleja y requiere espacio para los conductos.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Producci\u00f3n de agua caliente sanitaria (ACS)<\/h3>\n\n\n\n<p>Adem\u00e1s de la calefacci\u00f3n, las<a href=\"https:\/\/ecoforest.com\/es\/bomba-de-calor\/aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/bomba-de-calor\/aerotermia\/\"> bombas de calor aerot\u00e9rmicas<\/a> pueden ser utilizadas para calentar el agua que se usa en la vivienda (duchas, grifos, etc.).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ventajas<\/strong>: Proporciona un sistema integrado de calefacci\u00f3n y agua caliente, aprovechando la eficiencia de la aerotermia.<\/li>\n\n\n\n<li><strong>Desventajas<\/strong>: En zonas con inviernos muy fr\u00edos, puede requerirse un apoyo adicional para calentar el agua a las temperaturas deseadas.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPara qu\u00e9 se utiliza la aerotermia?<\/h2>\n\n\n\n<p>La aerotermia es una tecnolog\u00eda que aprovecha la <strong>energ\u00eda del ambiente<\/strong> para proporcionar calefacci\u00f3n, refrigeraci\u00f3n y agua caliente sanitaria en edificaciones.&nbsp;<\/p>\n\n\n\n<p>Utiliza una <strong>bomba de calor,<\/strong> en muchos casos reversible, para extraer o liberar calor del aire exterior. Entre sus aplicaciones m\u00e1s destacadas encontramos:<\/p>\n\n\n\n<p><strong>Calefacci\u00f3n:<\/strong> Puede ser utilizada en conjunto con sistemas como suelo radiante por radiadores, ofreciendo una distribuci\u00f3n uniforme del calor en las viviendas, especialmente en viviendas de nueva construcci\u00f3n dise\u00f1adas para ser energ\u00e9ticamente eficientes.<\/p>\n\n\n\n<p><strong>Refrigeraci\u00f3n:<\/strong> La bomba de calor reversible puede invertir su funcionamiento para aportar refrigeraci\u00f3n en verano, funcionando de manera similar a un sistema de aire acondicionado por conductos.<\/p>\n\n\n\n<p><strong>Agua caliente sanitaria:<\/strong> Mediante un dep\u00f3sito de agua caliente, la aerotermia puede proporcionar agua caliente para usos dom\u00e9sticos, como duchas, lavado de manos o cocina. <\/p>\n\n\n\n<p><strong>Integraci\u00f3n con energ\u00eda solar: <\/strong>En algunas instalaciones, la aerotermia se combina con placas solares, en especial con sistemas de energ\u00eda solar fotovoltaica, para obtener un sistema mixto que aprovecha tanto la energ\u00eda aerot\u00e9rmica como la solar, optimizando as\u00ed la eficiencia y la sostenibilidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas y desventajas de la aerotermia<\/h2>\n\n\n\n<p>La aerotermia presenta una serie de ventajas y desventajas que es importante considerar al evaluarla como soluci\u00f3n energ\u00e9tica. A continuaci\u00f3n, te presento un resumen de ambos aspectos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Funciona con energ\u00eda renovable<\/h3>\n\n\n\n<p>Decimos que la aerotermia funciona con energ\u00eda renovable porque se basa en aprovechar la energ\u00eda t\u00e9rmica almacenada en el aire exterior, una fuente inagotable y constantemente renovada, para proporcionar calefacci\u00f3n, refrigeraci\u00f3n y\/o agua caliente sanitaria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Origen de la energ\u00eda<\/h3>\n\n\n\n<p>&nbsp;La energ\u00eda que la aerotermia utiliza proviene directamente del ambiente.&nbsp;<\/p>\n\n\n\n<p>El aire, incluso en condiciones fr\u00edas, siempre contiene alguna cantidad de energ\u00eda t\u00e9rmica.&nbsp;<\/p>\n\n\n\n<p>Esta energ\u00eda t\u00e9rmica se origina, en gran medida, de la radiaci\u00f3n solar que calienta la Tierra y, por ende, el aire que nos rodea.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2-1024x640.png\" alt=\"aerotermia aire acondicionado\" class=\"wp-image-36318\" title=\"\" srcset=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2-1024x640.png 1024w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2-300x188.png 300w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2-768x480.png 768w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2-1536x960.png 1536w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/2.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Eficiencia y Coeficiente de Rendimiento (COP)<\/h3>\n\n\n\n<p>Aunque las bombas de calor aerot\u00e9rmicas requieren electricidad para funcionar, suelen ser extremadamente eficientes.<\/p>\n\n\n\n<p>Esto significa que por cada unidad de electricidad que consumen, pueden proporcionar m\u00faltiples unidades de energ\u00eda t\u00e9rmica.&nbsp;<\/p>\n\n\n\n<p>En muchos casos, el COP puede ser de 3, 4 o incluso superior, lo que significa que por cada kilovatio-hora de electricidad consumida, se obtienen 3 o 4&nbsp; kW hora de energ\u00eda t\u00e9rmica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reducci\u00f3n de emisiones<\/h3>\n\n\n\n<p>Al reemplazar o reducir el uso de sistemas de calefacci\u00f3n basados en combustibles f\u00f3siles, como el gas natural o el petr\u00f3leo, la aerotermia puede disminuir significativamente las emisiones de gases de efecto invernadero.&nbsp;<\/p>\n\n\n\n<p>Si adem\u00e1s la electricidad utilizada para alimentar la bomba de calor proviene de fuentes renovables, como la solar o la e\u00f3lica, el impacto medioambiental se reduce a\u00fan m\u00e1s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Regeneraci\u00f3n constante<\/h3>\n\n\n\n<p>A diferencia de los combustibles f\u00f3siles que son finitos y se agotan con el uso, la energ\u00eda del aire se renueva constantemente.&nbsp;<\/p>\n\n\n\n<p>No importa cu\u00e1nto se utilice la aerotermia; el aire seguir\u00e1 conteniendo energ\u00eda t\u00e9rmica gracias a la radiaci\u00f3n solar y otros fen\u00f3menos naturales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reconocimiento oficial<\/h3>\n\n\n\n<p>En muchos pa\u00edses y regiones, la aerotermia es reconocida oficialmente como una fuente de energ\u00eda renovable.&nbsp;<\/p>\n\n\n\n<p>Esto se traduce en pol\u00edticas de fomento, incentivos fiscales y subvenciones para promover su instalaci\u00f3n y uso.<\/p>\n\n\n\n<p>Decimos que la aerotermia funciona con energ\u00eda renovable porque se basa en aprovechar una fuente de energ\u00eda inagotable, constante y respetuosa con el medio ambiente: el aire que nos rodea.&nbsp;<\/p>\n\n\n\n<p>Esta tecnolog\u00eda, al utilizar predominantemente la energ\u00eda del ambiente y minimizar la dependencia de fuentes no renovables, se alinea con los objetivos de sostenibilidad y protecci\u00f3n medioambiental que rigen el desarrollo energ\u00e9tico actual.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Alta eficiencia energ\u00e9tica<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Multiplicaci\u00f3n de la energ\u00eda: <\/strong>Las bombas de calor aerot\u00e9rmicas no \u00abgeneran\u00bb calor en el sentido tradicional, sino que \u00abtrasladan\u00bb calor de un lugar a otro. Por cada unidad de energ\u00eda el\u00e9ctrica que consumen, son capaces de proporcionar varias unidades de energ\u00eda t\u00e9rmica. Por ejemplo, una bomba de calor con un COP de 4 puede proporcionar 4 unidades de energ\u00eda t\u00e9rmica por cada unidad de energ\u00eda el\u00e9ctrica consumida.<\/li>\n\n\n\n<li><strong>Aprovechamiento de la energ\u00eda ambiental: <\/strong>Aunque pueda parecer sorprendente, el aire exterior, incluso a temperaturas bajo cero, contiene energ\u00eda t\u00e9rmica. Las bombas de calor aerot\u00e9rmicas son capaces de extraer esta energ\u00eda y usarla para calefacci\u00f3n. Esta capacidad de aprovechar la energ\u00eda ambiental es lo que hace que la aerotermia sea tan eficiente en comparaci\u00f3n con sistemas que generan calor desde cero, como las resistencias el\u00e9ctricas.<\/li>\n\n\n\n<li><strong>Funcionamiento a bajas temperaturas:<\/strong> Sistemas como el suelo radiante funcionan a temperaturas m\u00e1s bajas que los radiadores tradicionales. Cuando se combina con la aerotermia, que es eficiente proporcionando calor a bajas temperaturas, se obtiene un sistema muy eficiente energ\u00e9ticamente.<\/li>\n\n\n\n<li><strong>Refrigeraci\u00f3n y calefacci\u00f3n:<\/strong> Las bombas de calor no solo pueden calentar un espacio, sino que tambi\u00e9n pueden enfriarlo. Al invertir su funcionamiento, una bomba de calor puede extraer el calor del interior de una vivienda y liberarlo al exterior, proporcionando refrigeraci\u00f3n en los meses m\u00e1s calurosos. Esta versatilidad mejora la eficiencia general del sistema durante todo el a\u00f1o.<\/li>\n\n\n\n<li><strong>Producci\u00f3n de agua caliente:<\/strong> Muchos sistemas aerot\u00e9rmicos tambi\u00e9n est\u00e1n dise\u00f1ados para proporcionar agua caliente sanitaria (ACS). Esto significa que se puede tener un \u00fanico sistema eficiente para calefacci\u00f3n, refrigeraci\u00f3n y ACS, en lugar de depender de m\u00faltiples sistemas.<\/li>\n\n\n\n<li><strong>Tecnolog\u00eda avanzada:<\/strong> Las bombas de calor modernas incorporan tecnolog\u00eda avanzada, como compresores que invierten y que adaptan su funcionamiento a las necesidades reales del espacio, operando a capacidad parcial cuando la demanda es baja, lo que incrementa a\u00fan m\u00e1s la eficiencia.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Tama\u00f1o<\/h3>\n\n\n\n<p>El tama\u00f1o y espacio requerido para una instalaci\u00f3n de aerotermia dependen de varios factores, incluidos el tipo de vivienda, las necesidades de climatizaci\u00f3n, el clima local y el modelo de bomba de calor seleccionado.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, podemos brindarte una visi\u00f3n general de lo que se podr\u00eda necesitar:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Unidad exterior:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tama\u00f1o:<\/strong> Las dimensiones var\u00edan seg\u00fan la potencia y el modelo, pero muchas unidades para la<a href=\"https:\/\/ecoforest.com\/es\/proyectos\/espana-vivienda-unifamiliar-con-aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/proyectos\/espana-vivienda-unifamiliar-con-aerotermia\/\"> instalaci\u00f3n de aerotermia en viviendas unifamiliares<\/a> son comparables en tama\u00f1o a las unidades exteriores de aire acondicionado.<\/li>\n\n\n\n<li><strong>Ubicaci\u00f3n:<\/strong> Debe estar en un lugar accesible para su mantenimiento, alejada de ventanas y puertas para evitar molestias por ruido, y en una posici\u00f3n donde el aire circule libremente.<\/li>\n\n\n\n<li><strong>Espacio adicional: <\/strong>Es aconsejable dejar un espacio libre alrededor de la unidad para facilitar el mantenimiento y asegurar una circulaci\u00f3n de aire adecuada.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Unidad interior (si el sistema es de tipo split):<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tama\u00f1o:<\/strong> Suele ser similar al de una caldera mural de gas, aunque las dimensiones pueden variar seg\u00fan el modelo.<\/li>\n\n\n\n<li><strong>Ubicaci\u00f3n:<\/strong> Normalmente se instala en un cuarto t\u00e9cnico, lavadero, trastero o similar. Debe ser un lugar seco y protegido.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Sistemas de distribuci\u00f3n de calor:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Suelo radiante:<\/strong> Requiere una instalaci\u00f3n bajo el suelo, por lo que no ocupa espacio visible, pero s\u00ed es necesario considerar la colocaci\u00f3n de colectores y la instalaci\u00f3n de tuber\u00edas.<\/li>\n\n\n\n<li><strong>Radiadores de baja temperatura<\/strong>: Ocupan espacio en las paredes de las habitaciones.<\/li>\n\n\n\n<li><strong>Fan coils: <\/strong>Dependiendo del modelo, pueden ser unidades de pared, techo o suelo. Es necesario considerar el espacio que ocupan y su integraci\u00f3n est\u00e9tica en la habitaci\u00f3n.<\/li>\n\n\n\n<li><strong>Sistemas de conductos:<\/strong> Se instalan en falsos techos o espacios ocultos, por lo que se debe considerar el espacio necesario para su alojamiento y mantenimiento.<\/li>\n\n\n\n<li><strong>Espacio para tuber\u00edas y conexiones:<\/strong> Se debe planificar la ruta de las tuber\u00edas que conectan las unidades interior y exterior, as\u00ed como las tuber\u00edas de distribuci\u00f3n de calor o fr\u00edo en el caso del suelo radiante o los fan coils.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Espacio para controles y termostatos<\/h3>\n\n\n\n<p>Estos suelen ser peque\u00f1os y se montan en las paredes, pero es importante considerar su ubicaci\u00f3n para un acceso y control f\u00e1ciles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCompatibilidad con radiadores?<\/h3>\n\n\n\n<p>La aerotermia, a trav\u00e9s de las bombas de calor, es compatible con radiadores, pero hay algunas consideraciones importantes a tener en cuenta:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tipo de Radiador:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Radiadores convencionales:<\/strong> Estos est\u00e1n dise\u00f1ados para trabajar con temperaturas de agua alrededor de 70\u00b0C a 80\u00b0C, que es lo que proporcionan t\u00edpicamente las calderas tradicionales. Las bombas de calor aerot\u00e9rmicas, en general, proporcionan agua a temperaturas m\u00e1s bajas (aproximadamente entre 35\u00b0C y 55\u00b0C). Esto significa que si se utilizan radiadores convencionales con aerotermia, es posible que no proporcionen el mismo rendimiento calor\u00edfico.<\/li>\n\n\n\n<li><strong>Radiadores de baja temperatura: <\/strong>Son la opci\u00f3n m\u00e1s adecuada para la aerotermia. Est\u00e1n dise\u00f1ados para funcionar eficientemente con temperaturas de agua m\u00e1s bajas, en el rango que proporciona una bomba de calor.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Eficiencia de la Bomba de Calor:<\/h3>\n\n\n\n<p>La eficiencia de una bomba de calor (COP) generalmente disminuye a medida que se requiere una temperatura del agua m\u00e1s alta.&nbsp;<\/p>\n\n\n\n<p>Esto significa que si se necesita calentar agua a temperaturas m\u00e1s elevadas para radiadores convencionales, la bomba de calor puede consumir m\u00e1s electricidad para hacerlo, reduciendo su eficiencia general.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3-1024x640.jpg\" alt=\"instalaci\u00f3n de aerotermia con radiadores\" class=\"wp-image-36325\" title=\"\" srcset=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3-1024x640.jpg 1024w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3-300x188.jpg 300w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3-768x480.jpg 768w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3-1536x960.jpg 1536w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/3.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Dimensionado:<\/h3>\n\n\n\n<p>Si se decide usar radiadores convencionales con aerotermia, puede ser necesario redimensionarlos (es decir, usar radiadores m\u00e1s grandes) para compensar la menor temperatura del agua y mantener la misma potencia calor\u00edfica en las habitaciones.<\/p>\n\n\n\n<p>Integraci\u00f3n con&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sistemas Existentes:<\/h3>\n\n\n\n<p>Si una vivienda ya tiene instalados radiadores convencionales y se quiere cambiar a aerotermia, se puede hacer.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, para obtener la m\u00e1xima eficiencia, podr\u00eda ser recomendable ajustar el sistema: esto podr\u00eda incluir la instalaci\u00f3n de radiadores de baja temperatura, o bien el redimensionamiento de los radiadores existentes.<\/p>\n\n\n\n<p>Es importante recalibrar y ajustar el sistema para garantizar que la bomba de calor funcione en las condiciones m\u00e1s eficientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Control de la Temperatura:<\/h3>\n\n\n\n<p>Es crucial tener un buen sistema de control y termostatos para garantizar que la bomba de calor y los radiadores trabajen juntos de manera eficiente y proporcionen la <a href=\"https:\/\/ecoforest.com\/es\/blog\/cual-es-la-temperatura-ideal-para-una-casa-en-verano\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/blog\/cual-es-la-temperatura-ideal-para-una-casa-en-verano\/\">temperatura deseada en las habitaciones<\/a>.<\/p>\n\n\n\n<p>Mientras que la aerotermia es compatible con radiadores, es importante tener en cuenta el tipo de radiador, el dimensionado y la temperatura de funcionamiento para garantizar una operaci\u00f3n eficiente.&nbsp;<\/p>\n\n\n\n<p>Si se est\u00e1 considerando combinar radiadores existentes con una bomba de calor aerot\u00e9rmica, es aconsejable consultar a un especialista para evaluar la mejor soluci\u00f3n y realizar cualquier ajuste necesario.<\/p>\n\n\n\n<p>Si bien es compatible con radiadores de baja temperatura, su rendimiento \u00f3ptimo se alcanza con sistemas de suelo radiante, maximizando su eficiencia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cero emisiones<\/h3>\n\n\n\n<p>La aerotermia, como sistema de climatizaci\u00f3n y producci\u00f3n de agua caliente, es una tecnolog\u00eda que, en comparaci\u00f3n con sistemas convencionales basados en combustibles f\u00f3siles, tiene un perfil mucho m\u00e1s bajo en cuanto a emisiones directas de gases contaminantes o gases de efecto invernadero.<\/p>\n\n\n\n<p><strong>Sin Emisiones Directas:<\/strong> La aerotermia utiliza una bomba de calor para extraer energ\u00eda del aire ambiente. No requiere combusti\u00f3n, lo que significa que no produce emisiones directas de CO2 ni otros contaminantes atmosf\u00e9ricos en el lugar de uso.<\/p>\n\n\n\n<p><strong>Dependencia de la Fuente El\u00e9ctrica: <\/strong>Aunque la aerotermia en s\u00ed misma no produce emisiones directas, la electricidad que alimenta la bomba de calor podr\u00eda generar emisiones si proviene de fuentes no renovables. Por lo tanto, el perfil de \u00abcero emisiones\u00bb es m\u00e1s exacto cuando la energ\u00eda el\u00e9ctrica proviene de fuentes renovables como la e\u00f3lica, solar o hidroel\u00e9ctrica.<\/p>\n\n\n\n<p><strong>Comparaci\u00f3n con Sistemas Convencionales: <\/strong>Al compararla con sistemas convencionales como calderas de gas, gasoil o carb\u00f3n, la aerotermia tiene un impacto ambiental mucho menor. Estos sistemas convencionales dependen de la combusti\u00f3n, lo que resulta en emisiones de CO2 y otros contaminantes.<\/p>\n\n\n\n<p><strong>Eficiencia y Reducci\u00f3n de Emisiones:<\/strong> Dado que la aerotermia es altamente eficiente (puede generar m\u00e1s energ\u00eda t\u00e9rmica de la que consume en forma de electricidad), reduce la demanda total de energ\u00eda y, por lo tanto, las emisiones asociadas con su producci\u00f3n.<\/p>\n\n\n\n<p><strong>Integraci\u00f3n con Energ\u00edas Renovables:<\/strong> La aerotermia puede integrarse con sistemas de energ\u00eda solar fotovoltaica o e\u00f3lica para crear soluciones de energ\u00eda completamente renovables, reforzando a\u00fan m\u00e1s su perfil de cero emisiones.<\/p>\n\n\n\n<p><strong>Contribuci\u00f3n a Objetivos Clim\u00e1ticos<\/strong>: Adoptar tecnolog\u00edas como la aerotermia es fundamental para alcanzar los objetivos clim\u00e1ticos globales y reducir las emisiones a cero o niveles cercanos a cero en sectores como la calefacci\u00f3n y refrigeraci\u00f3n residencial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema polivalente<\/h3>\n\n\n\n<p>Decimos que la aerotermia es un sistema polivalente debido a su versatilidad y capacidad para desempe\u00f1ar m\u00faltiples funciones a partir de un \u00fanico sistema.&nbsp;<\/p>\n\n\n\n<p>Espec\u00edficamente, la aerotermia puede proporcionar calefacci\u00f3n, refrigeraci\u00f3n y agua caliente sanitaria utilizando la misma infraestructura.&nbsp;<\/p>\n\n\n\n<p><strong>Calefacci\u00f3n y Refrigeraci\u00f3n: <\/strong>Las bombas de calor aerot\u00e9rmicas son reversibles. En invierno, extraen calor del aire exterior (incluso cuando hace fr\u00edo) y lo transfieren al interior para calentar un edificio. En verano, invierten el proceso, extrayendo calor del interior del edificio y liber\u00e1ndolo al exterior para refrigerar el espacio.<\/p>\n\n\n\n<p><strong>Agua Caliente Sanitaria (ACS):<\/strong> Adem\u00e1s de la calefacci\u00f3n y refrigeraci\u00f3n, la aerotermia puede calentar agua para uso dom\u00e9stico, proporcionando agua caliente para duchas, lavado de manos, cocina, etc. Esto se logra a trav\u00e9s de la integraci\u00f3n de la bomba de calor con un dep\u00f3sito de agua caliente.<\/p>\n\n\n\n<p><strong>Compatibilidad con Otros Sistemas:<\/strong> La aerotermia puede integrarse f\u00e1cilmente con otros sistemas de calefacci\u00f3n y refrigeraci\u00f3n, como el suelo radiante o los radiadores convencionales. Adem\u00e1s, es posible combinarla con sistemas de energ\u00eda solar fotovoltaica para crear una soluci\u00f3n energ\u00e9tica a\u00fan m\u00e1s sostenible.<\/p>\n\n\n\n<p><strong>Eficiencia Energ\u00e9tica en Diversos Modos:<\/strong> Dado que la aerotermia utiliza la energ\u00eda contenida en el aire (una fuente renovable) para funcionar, es eficiente en todos sus modos de operaci\u00f3n, ya sea calefacci\u00f3n, refrigeraci\u00f3n o producci\u00f3n de ACS.<\/p>\n\n\n\n<p><strong>Respuesta a Diferentes Demandas Clim\u00e1ticas:<\/strong> En regiones con estaciones clim\u00e1ticas marcadas, donde se necesite calefacci\u00f3n en invierno y refrigeraci\u00f3n en verano, la aerotermia es especialmente \u00fatil por su capacidad para adaptarse a estas demandas cambiantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Precios de Instalaci\u00f3n de la aerotermia<\/h2>\n\n\n\n<p>El precio de instalaci\u00f3n de un sistema de aerotermia puede variar significativamente en funci\u00f3n de diversos factores.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Factores que influyen en el precio:<\/h3>\n\n\n\n<p><strong>Capacidad y Modelo: <\/strong>Los equipos de mayor capacidad o con caracter\u00edsticas t\u00e9cnicas avanzadas suelen ser m\u00e1s caros.<\/p>\n\n\n\n<p><strong>Tipo de Instalaci\u00f3n:<\/strong> Dependiendo de si es para calefacci\u00f3n, refrigeraci\u00f3n, agua caliente sanitaria o una combinaci\u00f3n de estos, el precio puede variar.<\/p>\n\n\n\n<p><strong>Integraci\u00f3n con Otros Sistemas: <\/strong>Si decides integrar la aerotermia con, por ejemplo, suelo radiante, radiadores o un sistema de energ\u00eda solar, esto puede afectar el coste total.<\/p>\n\n\n\n<p><strong>Marca y Calidad: <\/strong>Algunas marcas reconocidas o de alta calidad pueden tener precios m\u00e1s elevados.<\/p>\n\n\n\n<p><strong>Requerimientos del Sitio: <\/strong>La preparaci\u00f3n del sitio, las necesidades de infraestructura y las posibles adaptaciones al edificio o vivienda pueden influir en el coste.<\/p>\n\n\n\n<p><strong>Mano de Obra: <\/strong>Dependiendo de la regi\u00f3n, la experiencia del instalador y la complejidad de la instalaci\u00f3n, los costes laborales pueden variar.<\/p>\n\n\n\n<p><strong>Zona geogr\u00e1fica: <\/strong>Los precios pueden fluctuar seg\u00fan el pa\u00eds o la regi\u00f3n, debido a diferencias en costes laborales, impuestos, demanda y otros factores regionales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1nto se ahorra instalando aerotermia?<\/h2>\n\n\n\n<p>El <a href=\"https:\/\/ecoforest.com\/es\/blog\/cuanto-podemos-ahorrar-con-aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/blog\/cuanto-podemos-ahorrar-con-aerotermia\/\">ahorro que se puede obtener con un sistema de aerotermia<\/a> en comparaci\u00f3n con otros sistemas de calefacci\u00f3n y refrigeraci\u00f3n tradicionales var\u00eda seg\u00fan diferentes factores.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, es ampliamente aceptado que la aerotermia puede generar ahorros significativos a largo plazo.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Eficiencia del Sistema:<\/strong> Las bombas de calor aerot\u00e9rmicas suelen ser muy eficientes. Por cada unidad de electricidad que consumen, pueden generar varias unidades de calor, lo que se traduce en un Coeficiente de Rendimiento (COP) de 3, 4 o incluso m\u00e1s en algunos modelos. Esto significa que, en t\u00e9rminos de producci\u00f3n de calor, una bomba de calor aerot\u00e9rmica puede ser hasta 3 o 4 veces m\u00e1s eficiente que los calentadores el\u00e9ctricos directos.<\/li>\n\n\n\n<li><strong>Comparaci\u00f3n con otros Combustibles: <\/strong>Si se compara con sistemas de calefacci\u00f3n basados en gas\u00f3leo, propano o electricidad directa, la aerotermia suele ser m\u00e1s econ\u00f3mica en t\u00e9rminos de coste operativo. Dependiendo de la ubicaci\u00f3n y el precio de la electricidad y otros combustibles, los ahorros pueden oscilar entre el 30% y el 75%.<\/li>\n\n\n\n<li><strong>Clima Local: <\/strong>En \u00e1reas con inviernos muy fr\u00edos, la eficiencia de la bomba de calor puede disminuir, lo que significa que el sistema trabajar\u00e1 m\u00e1s para extraer calor del aire exterior. Sin embargo, las tecnolog\u00edas modernas han mejorado la eficiencia de las bombas de calor en condiciones de fr\u00edo extremo.<\/li>\n\n\n\n<li><strong>Instalaci\u00f3n Previa:<\/strong> Si una vivienda cuenta con un sistema de calefacci\u00f3n anticuado y poco eficiente, el cambio a aerotermia se traducir\u00e1 en ahorros m\u00e1s significativos.<\/li>\n\n\n\n<li><strong>Usos m\u00faltiples: <\/strong>Las bombas de calor aerot\u00e9rmicas no solo proporcionan calefacci\u00f3n, sino que tambi\u00e9n pueden ofrecer refrigeraci\u00f3n y agua caliente sanitaria. Esta multifuncionalidad puede llevar a ahorros adicionales si se compara con la operaci\u00f3n y mantenimiento de m\u00faltiples sistemas.<\/li>\n\n\n\n<li><strong>Incentivos y subvenciones:<\/strong> En muchas regiones, las instalaciones de aerotermia pueden beneficiarse de incentivos gubernamentales, subvenciones o tarifas de electricidad reducidas, lo que puede mejorar a\u00fan m\u00e1s el retorno de la inversi\u00f3n.<\/li>\n\n\n\n<li><strong>Mantenimiento:<\/strong> Aunque cualquier sistema de calefacci\u00f3n y refrigeraci\u00f3n requiere mantenimiento, las bombas de calor aerot\u00e9rmicas suelen tener requisitos de mantenimiento m\u00e1s bajos en comparaci\u00f3n con los sistemas a base de combustibles f\u00f3siles. Esto puede traducirse en ahorros a largo plazo.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4-1024x640.png\" alt=\"merece la pena la aerotermia\" class=\"wp-image-36332\" title=\"\" srcset=\"https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4-1024x640.png 1024w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4-300x188.png 300w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4-768x480.png 768w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4-1536x960.png 1536w, https:\/\/ecoforest.com\/wp-content\/uploads\/2023\/10\/4.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Preguntas frecuentes sobre la aerotermia<\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1696324020829\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00bfPuedo generar agua caliente sanitaria \u201cACS\u201d por aerotermia?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>La aerotermia es una excelente opci\u00f3n para generar Agua Caliente Sanitaria (ACS). De hecho, es una de las aplicaciones m\u00e1s comunes de la aerotermia en muchos hogares y edificios. Veamos c\u00f3mo funciona y algunas de sus ventajas:<\/p>\n<p>Funcionamiento de la aerotermia para ACS:<\/p>\n<p><strong>Extracci\u00f3n de Energ\u00eda: <\/strong>La bomba de calor aerot\u00e9rmica extrae energ\u00eda t\u00e9rmica del aire exterior. Esta energ\u00eda puede ser captada incluso en condiciones de bajas temperaturas exteriores.<\/p>\n<p><strong>Transferencia de Calor:<\/strong> A trav\u00e9s de un proceso de compresi\u00f3n y expansi\u00f3n de un refrigerante, la bomba de calor eleva la temperatura de esta energ\u00eda extra\u00edda y la transfiere al agua almacenada en un dep\u00f3sito o acumulador.<\/p>\n<p><strong>Dep\u00f3sito de Agua Caliente: <\/strong>Una vez calentada, el agua se almacena en un dep\u00f3sito especial para ACS, listo para ser utilizado en las instalaciones sanitarias del hogar o edificio.<\/p>\n<p>Ventajas de usar aerotermia para ACS:<\/p>\n<p><strong>Eficiencia:<\/strong> Por cada unidad de electricidad que la bomba de calor consume, puede proporcionar varias unidades de calor, lo que la hace m\u00e1s eficiente que muchos sistemas el\u00e9ctricos convencionales de calentamiento de agua.<\/p>\n<p><strong>Reducci\u00f3n de Emisiones:<\/strong> Al no requerir combusti\u00f3n y al reducir el consumo de electricidad en comparaci\u00f3n con resistencias el\u00e9ctricas tradicionales, se generan menos emisiones de CO2 y otros contaminantes.<\/p>\n<p><strong>Ahorro Econ\u00f3mico: <\/strong>Aunque la inversi\u00f3n inicial puede ser m\u00e1s alta que en sistemas convencionales, el ahorro en las facturas de electricidad a lo largo del tiempo puede ser significativo.<\/p>\n<p><strong>Sostenibilidad:<\/strong> La aerotermia aprovecha la energ\u00eda presente en el aire, una fuente renovable, para calentar el agua, disminuyendo la dependencia de fuentes de energ\u00eda no renovables.<\/p>\n<p><strong>Seguridad<\/strong>: Al no haber combusti\u00f3n, se eliminan los riesgos asociados con escapes de gas o incendios que pueden presentarse en sistemas de gas.<\/p>\n<p><strong>Versatilidad: <\/strong>Adem\u00e1s de proporcionar ACS, la misma bomba de calor puede utilizarse para calefacci\u00f3n en invierno y refrigeraci\u00f3n en verano.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1696324126905\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00bfEs eficiente la instalaci\u00f3n de aerotermia?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>La aerotermia es reconocida por ser un<strong> sistema altamente eficiente <\/strong>en t\u00e9rminos de climatizaci\u00f3n y producci\u00f3n de Agua Caliente Sanitaria (ACS). Su eficiencia se basa en varios principios y caracter\u00edsticas:<\/p>\n<p><strong>Coeficiente de Rendimiento (COP): <\/strong>Uno de los indicadores clave de la eficiencia de una bomba de calor aerot\u00e9rmica es el Coeficiente de Rendimiento (COP).\u00a0<\/p>\n<p><strong>Fuente Renovable:<\/strong> La aerotermia extrae alrededor del 70-80% de la energ\u00eda del aire exterior, que es una fuente inagotable y renovable. Esto significa que solo se necesita aportar un 20-30% de energ\u00eda (generalmente en forma de electricidad) para hacer funcionar el sistema.<\/p>\n<p><strong>Sistemas Reversibles:<\/strong> Muchas bombas de calor aerot\u00e9rmicas son reversibles, lo que significa que pueden proporcionar calefacci\u00f3n en invierno y refrigeraci\u00f3n en verano. Esta dualidad mejora la eficiencia global del sistema a lo largo del a\u00f1o.<\/p>\n<p><strong>Reducci\u00f3n del Consumo El\u00e9ctrico:<\/strong> Comparada con sistemas el\u00e9ctricos de resistencia directa para calefacci\u00f3n o calentamiento de agua, la aerotermia utiliza significativamente menos electricidad para producir la misma cantidad de calor.<\/p>\n<p><strong>Menor Impacto Ambiental:<\/strong> Debido a su alta eficiencia y uso de energ\u00eda renovable, la aerotermia tiene un menor impacto ambiental en comparaci\u00f3n con los sistemas de calefacci\u00f3n basados en combustibles f\u00f3siles.<\/p>\n<p><strong>Integraci\u00f3n con Otros Sistemas:<\/strong> La aerotermia puede combinarse eficientemente con otros sistemas de calefacci\u00f3n o enfriamiento, como el suelo radiante, que es especialmente eficiente en t\u00e9rminos de distribuci\u00f3n de calor.<\/p>\n<p><strong>Adaptabilidad a Diferentes Condiciones:<\/strong> Las bombas de calor modernas pueden operar eficientemente en una amplia gama de temperaturas exteriores, incluso en zonas clim\u00e1ticas muy fr\u00edas.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1696324155455\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00bfFunciona correctamente la aerotermia con temperaturas bajo cero?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Puede funcionar correctamente con temperaturas bajo cero. No obstante, hay algunas <strong>consideraciones<\/strong> importantes al respecto:<\/p>\n<p><strong>Tecnolog\u00eda Moderna:<\/strong> Las bombas de calor aerot\u00e9rmicas modernas est\u00e1n dise\u00f1adas para funcionar eficientemente en temperaturas exteriores muy bajas. Algunos modelos pueden operar de manera efectiva con temperaturas tan bajas como -20\u00b0C o incluso -25\u00b0C, aunque la eficiencia (COP) tiende a disminuir a medida que la temperatura exterior se reduce.<\/p>\n<p><strong>Desescarche: <\/strong>Cuando la temperatura exterior es baja y hay humedad, puede formarse hielo en el evaporador de la unidad exterior. Para evitar que esto afecte su funcionamiento, las bombas de calor incluyen ciclos de desescarche que invierten temporalmente su funcionamiento para derretir el hielo acumulado.<\/p>\n<p><strong>Reducci\u00f3n de la Capacidad:<\/strong> Aunque la aerotermia sigue funcionando con temperaturas bajo cero, la capacidad de la bomba de calor para extraer calor del aire disminuye a medida que la temperatura desciende. Esto puede requerir que el sistema funcione durante m\u00e1s tiempo para satisfacer la demanda de calefacci\u00f3n o que se utilice una fuente auxiliar de calor en los d\u00edas m\u00e1s fr\u00edos.<\/p>\n<p><strong>Aerotermia de Alta Temperatura: <\/strong>Existen sistemas de aerotermia de alta temperatura dise\u00f1ados espec\u00edficamente para zonas clim\u00e1ticas muy fr\u00edas. Estos sistemas pueden producir agua caliente a temperaturas m\u00e1s elevadas, lo que es ideal para sistemas de calefacci\u00f3n tradicionales, como radiadores.<\/p>\n<p><strong>Integraci\u00f3n con Sistemas Auxiliares:<\/strong> En zonas donde las temperaturas bajo cero son frecuentes o prolongadas, es com\u00fan que los sistemas de aerotermia se combinen con fuentes de calor auxiliares, como calderas o resistencias el\u00e9ctricas, para asegurar un suministro constante de calefacci\u00f3n durante los periodos m\u00e1s fr\u00edos.<\/p>\n<p><strong>Correcto Dimensionamiento:<\/strong> Para asegurarse de que la aerotermia funcione correctamente en condiciones de fr\u00edo extremo, es esencial que el sistema est\u00e9 adecuadamente dimensionado para las necesidades del edificio y las condiciones clim\u00e1ticas del lugar.<\/p>\n<p><strong>Aislamiento y Eficiencia del Edificio:<\/strong> Un edificio bien aislado y dise\u00f1ado para ser energ\u00e9ticamente eficiente har\u00e1 que la aerotermia funcione de manera m\u00e1s efectiva, incluso en temperaturas extremadamente bajas.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1696324186631\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00bfPuedo instalar aerotermia con radiadores?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Es posible<a href=\"https:\/\/ecoforest.com\/es\/blog\/5-razones-para-instalar-aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/blog\/5-razones-para-instalar-aerotermia\/\"> instalar aerotermia<\/a> con radiadores, pero hay algunas consideraciones importantes a tener en cuenta:<\/p>\n<p><strong>Temperatura del Agua:<\/strong> Los radiadores convencionales, especialmente los m\u00e1s antiguos, est\u00e1n dise\u00f1ados para trabajar con temperaturas de agua m\u00e1s altas (alrededor de 70\u00b0C a 80\u00b0C) que las proporcionadas por las bombas de calor aerot\u00e9rmicas est\u00e1ndar.\u00a0<\/p>\n<p>Las bombas de calor generalmente suministran agua a temperaturas de entre 35\u00b0C a 55\u00b0C. Por lo tanto, si usas radiadores convencionales con aerotermia, es posible que no alcancen su m\u00e1xima eficiencia o que no proporcionen el calor suficiente en d\u00edas muy fr\u00edos.<\/p>\n<p><strong>Radiadores de Baja Temperatura: <\/strong>Existen radiadores dise\u00f1ados espec\u00edficamente para funcionar a temperaturas m\u00e1s bajas, que son ideales para sistemas de aerotermia.\u00a0<\/p>\n<p>Estos radiadores de baja temperatura suelen ser m\u00e1s grandes o tienen m\u00e1s superficie de intercambio de calor, lo que les permite emitir la cantidad de calor adecuada a pesar de la menor temperatura del agua.<\/p>\n<p><strong>Aerotermia de Alta Temperatura: <\/strong>Hay bombas de calor de alta temperatura en el mercado que pueden generar agua a temperaturas m\u00e1s altas, adecuadas para sistemas de radiadores convencionales.\u00a0<\/p>\n<p>Si est\u00e1s considerando la aerotermia para una vivienda con radiadores existentes y no quieres cambiarlos, una bomba de calor de alta temperatura puede ser una buena opci\u00f3n.<\/p>\n<p><strong>Eficiencia y Consumo:<\/strong> Usar radiadores con aerotermia puede ser menos eficiente que combinarla con sistemas de suelo radiante dise\u00f1ados para trabajar con temperaturas m\u00e1s bajas. Sin embargo, sigue siendo m\u00e1s eficiente que muchos sistemas de calefacci\u00f3n convencionales.<\/p>\n<p><strong>Adaptabilidad:<\/strong> Si ya tienes radiadores instalados en tu vivienda y quieres cambiar a un sistema de aerotermia, es posible adaptar el sistema.\u00a0<\/p>\n<p>Sin embargo, es fundamental consultar con un especialista para asegurarse de que la bomba de calor est\u00e9 adecuadamente dimensionada y que los radiadores sean compatibles.<\/p>\n<p><strong>Combinaci\u00f3n con Otros Sistemas:<\/strong> Puedes combinar la aerotermia con otros sistemas de calefacci\u00f3n. Por ejemplo, puedes usar la aerotermia como fuente principal de calefacci\u00f3n y tener un sistema auxiliar (como una caldera) para los d\u00edas m\u00e1s fr\u00edos o para elevar la temperatura del agua si es necesario.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1696324230801\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00bfEs mejor aerotermia o gas natural?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u200b\u200bLa decisi\u00f3n entre aerotermia y gas natural depende de diversos factores, incluidos los costos operativos y de instalaci\u00f3n, las preocupaciones medioambientales, la eficiencia energ\u00e9tica, el tipo de vivienda y las condiciones clim\u00e1ticas locales.\u00a0<\/p>\n<p><em>Aerotermia:<\/em><\/p>\n<p><strong>Ventajas:<\/strong><\/p>\n<p>Energ\u00eda Renovable: La aerotermia utiliza el aire exterior, una fuente inagotable y renovable, para generar calor o fr\u00edo.<br \/>Eficiencia: Las bombas de calor aerot\u00e9rmicas tienen un alto coeficiente de rendimiento (COP), lo que significa que pueden producir m\u00e1s energ\u00eda de la que consumen, especialmente en temperaturas moderadas.<\/p>\n<p>Versatilidad: Las bombas de calor pueden ofrecer tanto calefacci\u00f3n como refrigeraci\u00f3n, y algunas incluso pueden producir agua caliente sanitaria (ACS).<\/p>\n<p>Reducci\u00f3n de Emisiones: Al no depender directamente de la combusti\u00f3n de combustibles f\u00f3siles, la aerotermia tiene un menor impacto en t\u00e9rminos de emisiones de CO2, especialmente si se combina con electricidad de fuentes renovables.<\/p>\n<p><strong>Desventajas:<\/strong><\/p>\n<p>Dependencia de la Electricidad: Aunque son eficientes, las bombas de calor requieren electricidad para funcionar, lo que puede afectar los costos operativos si los precios de la electricidad son altos.<\/p>\n<p>Rendimiento en Climas Extremadamente Fr\u00edos: Si bien las bombas de calor modernas funcionan en temperaturas bajo cero, su eficiencia puede disminuir en climas extremadamente fr\u00edos.<\/p>\n<p><em>Gas Natural:<\/em><\/p>\n<p><strong>Ventajas:<\/strong><\/p>\n<p>Eficiencia: Las calderas de gas natural modernas tienen una alta eficiencia y pueden convertir una gran proporci\u00f3n del gas consumido en calor \u00fatil.<\/p>\n<p>Rendimiento Constante: A diferencia de la aerotermia, las calderas de gas tienen un rendimiento m\u00e1s constante independientemente de las condiciones clim\u00e1ticas externas.<\/p>\n<p>Costo de Energ\u00eda: En algunas regiones, el gas natural puede ser m\u00e1s barato que la electricidad, lo que podr\u00eda resultar en menores costos operativos.<\/p>\n<p><strong>Desventajas:<\/strong><\/p>\n<p><strong>Emisiones de CO2:<\/strong> La combusti\u00f3n de gas natural produce emisiones de di\u00f3xido de carbono, contribuyendo al cambio clim\u00e1tico.<\/p>\n<p><strong>Dependencia de Suministro:<\/strong> Es necesario tener una conexi\u00f3n a la red de gas o un suministro regular de gas si no hay conexi\u00f3n disponible.<\/p>\n<p><strong>No Proporciona Refrigeraci\u00f3n: <\/strong>Las calderas de gas natural solo proporcionan calefacci\u00f3n y, en algunos casos, ACS. No ofrecen refrigeraci\u00f3n como las bombas de calor.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p><strong>Conclusi\u00f3n:<\/strong><\/p>\n\n\n\n<p>La elecci\u00f3n entre aerotermia y gas natural depender\u00e1 de tus prioridades y condiciones espec\u00edficas.&nbsp;<\/p>\n\n\n\n<p>Si buscas una soluci\u00f3n m\u00e1s ecol\u00f3gica y vers\u00e1til, y tienes acceso a electricidad a un precio razonable, la aerotermia podr\u00eda ser una excelente opci\u00f3n.<\/p>\n\n\n\n<p>&nbsp;Sin embargo, si vives en un \u00e1rea con inviernos extremadamente fr\u00edos y los precios del gas natural son competitivos, una caldera de gas natural podr\u00eda ser m\u00e1s adecuada.<\/p>\n\n\n\n<p>En resumen, la aerotermia se presenta como una<a href=\"https:\/\/ecoforest.com\/es\/blog\/cuanto-podemos-ahorrar-con-aerotermia\/\" data-type=\"link\" data-id=\"https:\/\/ecoforest.com\/es\/blog\/cuanto-podemos-ahorrar-con-aerotermia\/\"> alternativa eficiente y sostenible<\/a> para climatizar nuestro hogar y proveer agua caliente sanitaria, aprovechando la energ\u00eda renovable presente en el aire<\/p>\n\n\n\n<p><strong>\u00b7<\/strong> Es posible&nbsp;<strong>combinarlo con otras fuentes de energ\u00edas renovables<\/strong> pudiendo conseguir pr\u00e1cticamente el autoconsumo (\u00fanicamente la <a href=\"https:\/\/ecoforest.com\/es\/bomba-de-calor\/aerotermia\/\" data-type=\"URL\" data-id=\"https:\/\/ecoforest.com\/es\/bomba-de-calor\/aerotermia\/\">gama ecoAIR<\/a> junto con nuestros <a href=\"https:\/\/ecoforest.com\/es\/bomba-de-calor\/accesorios-para-bombas-de-calor\/\">gestores energ\u00e9ticos<\/a>).<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfC\u00f3mo funciona la aerotermia? - Ecoforest\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rd6mGiZ0JUQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La aerotermia es un sistema de climatizaci\u00f3n que aprovecha la energ\u00eda presente en el aire exterior para generar calefacci\u00f3n, refrigeraci\u00f3n y agua caliente sanitaria (ACS). Su funcionamiento se basa en una bomba de calor, la cual extrae calor del aire del entorno y lo transfiere al interior de un edificio para calentarlo, o realiza el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7,79],"tags":[],"class_list":["post-697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-aerotermia"],"acf":[],"featured_image_src_large":["https:\/\/ecoforest.com\/wp-content\/uploads\/2021\/06\/aerotermia-blog.jpg",1000,576,false],"author_info":{"display_name":"desarrollo","author_link":"https:\/\/ecoforest.com\/es\/author\/desarrollo\/"},"comment_info":0,"category_info":[{"term_id":7,"name":"Blog","slug":"blog","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":0,"count":341,"filter":"raw","cat_ID":7,"category_count":341,"category_description":"","cat_name":"Blog","category_nicename":"blog","category_parent":0},{"term_id":79,"name":"Aerotermia","slug":"aerotermia","term_group":0,"term_taxonomy_id":79,"taxonomy":"category","description":"","parent":78,"count":204,"filter":"raw","cat_ID":79,"category_count":204,"category_description":"","cat_name":"Aerotermia","category_nicename":"aerotermia","category_parent":78}],"tag_info":false,"taxonomy_info":{"category":[{"value":7,"label":"Blog"},{"value":79,"label":"Aerotermia"}]},"_links":{"self":[{"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/posts\/697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/comments?post=697"}],"version-history":[{"count":12,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/posts\/697\/revisions"}],"predecessor-version":[{"id":49396,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/posts\/697\/revisions\/49396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/media\/698"}],"wp:attachment":[{"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/media?parent=697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/categories?post=697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecoforest.com\/es\/wp-json\/wp\/v2\/tags?post=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}